{"id":1081781,"date":"2026-05-11T20:20:10","date_gmt":"2026-05-11T18:20:10","guid":{"rendered":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/"},"modified":"2026-04-22T17:18:04","modified_gmt":"2026-04-22T15:18:04","slug":"zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude","status":"publish","type":"immobilien","link":"https:\/\/carpe-sol.com\/de\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/","title":{"rendered":"ZAGREB &#8211; DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!!"},"content":{"rendered":"<p>Donja Dubrava &#8211; Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen.<\/p>\n<p>  Die Wohnung wird zum ersten Mal vermietet und ist ideal f\u00fcr eine Person oder ein Paar.<\/p>\n<p>  Es besteht aus einem Wohnzimmer mit K\u00fcche und Essbereich, einem separaten Schlafzimmer, einem Badezimmer und einem Balkon.<\/p>\n<p>  Zur Wohnung geh\u00f6ren ein eigener Parkplatz und ein Abstellraum.<\/p>\n<p>  Es ist mit einer Fu\u00dfbodenheizung mittels W\u00e4rmepumpe ausgestattet, was eine hohe Energieeffizienz und niedrige Betriebskosten erm\u00f6glicht.<\/p>\n<p>  Die Wohnung ist hell, funktional geschnitten und komfortabel f\u00fcr den Alltag.<\/p>\n<p>  Es befindet sich in ruhiger und \u00e4u\u00dferst g\u00fcnstiger Lage, in unmittelbarer N\u00e4he einer Stra\u00dfenbahnhaltestelle, Gesch\u00e4ften, Schulen, Kinderg\u00e4rten und allen Annehmlichkeiten, die f\u00fcr ein angenehmes und praktisches Leben notwendig sind, mit hervorragenden Verkehrsverbindungen ins Stadtzentrum und in andere Teile Zagrebs.<\/p>\n<p>  Dokumentation in Ordnung.<\/p>\n<p>  NUR UNTER DER NUMMERNUMMER 095 803 0771 ANRUFEN.<\/p>\n","protected":false},"author":0,"featured_media":1082734,"template":"","meta":{"_acf_changed":false,"footnotes":""},"building_condition":[252],"features":[172],"haus_typ":[],"heating":[],"kategorie":[290],"location_feature":[],"parking":[],"utility":[179,285,396],"class_list":["post-1081781","immobilien","type-immobilien","status-publish","has-post-thumbnail","hentry","building_condition-neu","features-balkon-de","kategorie-wohnung","utility-elektrizitaet","utility-kanal-de","utility-voda-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN<\/title>\n<meta name=\"description\" content=\"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN\" \/>\n<meta property=\"og:description\" content=\"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/\" \/>\n<meta property=\"og:site_name\" content=\"CARPE SOL IMMOBILIEN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/\",\"url\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/\",\"name\":\"ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN\",\"isPartOf\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg\",\"datePublished\":\"2026-05-11T18:20:10+00:00\",\"description\":\"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal\",\"breadcrumb\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg\",\"width\":810,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/carpe-sol.com\/hr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZAGREB &#8211; DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"name\":\"CARPE SOL IMMOBILIEN\",\"description\":\"Leben in Kroatien - Immobilien in Kroatien\",\"publisher\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\",\"name\":\"CARPE SOL IMMOBILIEN\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":393,\"height\":72,\"caption\":\"CARPE SOL IMMOBILIEN\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN","description":"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/","og_locale":"de_DE","og_type":"article","og_title":"ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN","og_description":"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal","og_url":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/","og_site_name":"CARPE SOL IMMOBILIEN","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/","url":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/","name":"ZAGREB - DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!! - CARPE SOL IMMOBILIEN","isPartOf":{"@id":"https:\/\/carpe-sol.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage"},"image":{"@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage"},"thumbnailUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg","datePublished":"2026-05-11T18:20:10+00:00","description":"Donja Dubrava - Ba\u010dka Stra\u00dfe, moderne, brandneue Zweizimmerwohnung zu vermieten, Fl\u00e4che 40 m2, in einem Neubau gelegen. Die Wohnung wird zum ersten Mal","breadcrumb":{"@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#primaryimage","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-04-07-at-16.34.43__4FUrgjFo-1200x1600-portrait-30.jpeg","width":810,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/carpe-sol.com\/immobilien\/zagreb-donja-dubrava-backa-strasse-zwei-zimmer-wohnung-zu-vermieten-neues-gebaeude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carpe-sol.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/"},{"@type":"ListItem","position":3,"name":"ZAGREB &#8211; DONJA DUBRAVA (Ba\u010dka-Stra\u00dfe), ZWEI-ZIMMER-WOHNUNG ZU VERMIETEN, NEUES GEB\u00c4UDE!!!"}]},{"@type":"WebSite","@id":"https:\/\/carpe-sol.com\/hr\/#website","url":"https:\/\/carpe-sol.com\/hr\/","name":"CARPE SOL IMMOBILIEN","description":"Leben in Kroatien - Immobilien in Kroatien","publisher":{"@id":"https:\/\/carpe-sol.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/carpe-sol.com\/hr\/#organization","name":"CARPE SOL IMMOBILIEN","url":"https:\/\/carpe-sol.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","width":393,"height":72,"caption":"CARPE SOL IMMOBILIEN"},"image":{"@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/1081781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/types\/immobilien"}],"version-history":[{"count":0,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/1081781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media\/1082734"}],"wp:attachment":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media?parent=1081781"}],"wp:term":[{"taxonomy":"building_condition","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/building_condition?post=1081781"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/features?post=1081781"},{"taxonomy":"haus_typ","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/haus_typ?post=1081781"},{"taxonomy":"heating","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/heating?post=1081781"},{"taxonomy":"kategorie","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/kategorie?post=1081781"},{"taxonomy":"location_feature","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/location_feature?post=1081781"},{"taxonomy":"parking","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/parking?post=1081781"},{"taxonomy":"utility","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/utility?post=1081781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}