{"id":597318,"date":"2025-11-21T04:36:21","date_gmt":"2025-11-21T02:36:21","guid":{"rendered":"https:\/\/carpe-sol.com\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/"},"modified":"2025-06-04T17:06:57","modified_gmt":"2025-06-04T15:06:57","slug":"zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu","status":"publish","type":"immobilien","link":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/","title":{"rendered":"ZADAR &#8211; ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!!"},"content":{"rendered":"<p>Zadar &#8211; Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022.<br \/>\n .<br \/>\n Es besteht aus einem Erdgeschoss und einem ersten Stock.<br \/>\n Erdgeschoss: Wohnzimmer + K\u00fcche + Esszimmer, Speisekammer, Badezimmer, WC, Terrasse und Loggia.<br \/>\n Etage: drei Schlafzimmer, Flur, zwei Badezimmer und zwei Loggien.<br \/>\n .<br \/>\n DAS HAUS BIETET EINEN SCH\u00d6NEN BLICK AUF DAS MEER UND DEN STRAND!!!<br \/>\n .<br \/>\n Es befindet sich in ausgezeichneter Lage, 20 m vom Meer und 170 m vom Sandstrand entfernt, in der N\u00e4he aller notwendigen Einrichtungen f\u00fcr einen angenehmen Urlaub und ein angenehmes Leben!!!<br \/>\n .<br \/>\n Es verf\u00fcgt \u00fcber einen Parkplatz.<br \/>\n .<br \/>\n Die Dokumentation ist in Ordnung.<\/p>\n","protected":false},"author":4,"featured_media":1012298,"template":"","meta":{"_acf_changed":false,"footnotes":""},"building_condition":[252],"features":[172,275,225],"haus_typ":[308],"heating":[175],"kategorie":[176],"location_feature":[167,259,256],"parking":[],"utility":[179,232,231,261,180,257,230,260],"class_list":["post-597318","immobilien","type-immobilien","status-publish","has-post-thumbnail","hentry","building_condition-neu","features-balkon-de","features-loggia-de","features-speisekammer","haus_typ-terrassiert","heating-wechselstrom","kategorie-haus","location_feature-beste-lage","location_feature-seeblick","location_feature-pogled-na-more","utility-elektrizitaet","utility-dsl-de","utility-klaergrube","utility-kanal","utility-telefon","utility-voda","utility-wasser","utility-wasser-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN<\/title>\n<meta name=\"description\" content=\"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN\" \/>\n<meta property=\"og:description\" content=\"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/\" \/>\n<meta property=\"og:site_name\" content=\"CARPE SOL IMMOBILIEN\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/09\/39176-568809346-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/\",\"url\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/\",\"name\":\"ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN\",\"isPartOf\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg\",\"datePublished\":\"2025-11-21T02:36:21+00:00\",\"description\":\"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:\",\"breadcrumb\":{\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg\",\"width\":1619,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/carpe-sol.com\/hr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZADAR &#8211; ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"name\":\"CARPE SOL IMMOBILIEN\",\"description\":\"Leben in Kroatien - Immobilien in Kroatien\",\"publisher\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\",\"name\":\"CARPE SOL IMMOBILIEN\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":393,\"height\":72,\"caption\":\"CARPE SOL IMMOBILIEN\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN","description":"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/","og_locale":"de_DE","og_type":"article","og_title":"ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN","og_description":"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:","og_url":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/","og_site_name":"CARPE SOL IMMOBILIEN","og_image":[{"width":1619,"height":1080,"url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/09\/39176-568809346-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/","url":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/","name":"ZADAR - ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!! - CARPE SOL IMMOBILIEN","isPartOf":{"@id":"https:\/\/carpe-sol.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage"},"image":{"@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage"},"thumbnailUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg","datePublished":"2025-11-21T02:36:21+00:00","description":"Zadar - Zaton, ein Reihenhaus zum Verkauf mit 118,34 m2 Wohnfl\u00e4che, Baujahr 2022. . Es besteht aus einem Erdgeschoss und einem ersten Stock. Erdgeschoss:","breadcrumb":{"@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#primaryimage","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2025\/11\/39176-568809346-1.jpg","width":1619,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/carpe-sol.com\/de\/immobilien\/zadar-zaton-haus-11834-m2-zu-verkaufen-aussicht-lage-neu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carpe-sol.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/"},{"@type":"ListItem","position":3,"name":"ZADAR &#8211; ZATON, HAUS 118,34 M2 ZU VERKAUFEN, AUSSICHT, LAGE, NEU!!!"}]},{"@type":"WebSite","@id":"https:\/\/carpe-sol.com\/hr\/#website","url":"https:\/\/carpe-sol.com\/hr\/","name":"CARPE SOL IMMOBILIEN","description":"Leben in Kroatien - Immobilien in Kroatien","publisher":{"@id":"https:\/\/carpe-sol.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/carpe-sol.com\/hr\/#organization","name":"CARPE SOL IMMOBILIEN","url":"https:\/\/carpe-sol.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","width":393,"height":72,"caption":"CARPE SOL IMMOBILIEN"},"image":{"@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/597318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/types\/immobilien"}],"author":[{"embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/597318\/revisions"}],"predecessor-version":[{"id":657422,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/597318\/revisions\/657422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media\/1012298"}],"wp:attachment":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media?parent=597318"}],"wp:term":[{"taxonomy":"building_condition","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/building_condition?post=597318"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/features?post=597318"},{"taxonomy":"haus_typ","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/haus_typ?post=597318"},{"taxonomy":"heating","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/heating?post=597318"},{"taxonomy":"kategorie","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/kategorie?post=597318"},{"taxonomy":"location_feature","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/location_feature?post=597318"},{"taxonomy":"parking","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/parking?post=597318"},{"taxonomy":"utility","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/utility?post=597318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}