{"id":717364,"date":"2026-06-27T04:14:05","date_gmt":"2026-06-27T02:14:05","guid":{"rendered":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/"},"modified":"2025-06-05T12:29:23","modified_gmt":"2025-06-05T10:29:23","slug":"pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage","status":"publish","type":"immobilien","link":"https:\/\/carpe-sol.com\/de\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/","title":{"rendered":"PAG &#8211; POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!!"},"content":{"rendered":"<p>Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige Bauweise.<br \/>\n.<br \/>\nEs besteht aus zwei Etagen:<br \/>\n &#8211; unten: drei Schlafzimmer, Flur, Badezimmer, Kleiderschrank und zwei Terrassen.<br \/>\n&#8211; Galerie: ein Schlafzimmer, Wohnzimmer + K\u00fcche + Esszimmer, Flur, Badezimmer und Terrasse.<br \/>\n.<br \/>\nDER MEERBLICK WIRD AUS DER WOHNUNG ANGEBOTEN!!!<br \/>\n.<br \/>\nEs befindet sich in einer ausgezeichneten Lage, 260 m vom Meer und dem ber\u00fchmten Strand von Dubrovnik entfernt, in der N\u00e4he aller notwendigen Annehmlichkeiten f\u00fcr einen angenehmen Urlaub!!!<br \/>\n.<br \/>\nEs verf\u00fcgt \u00fcber einen Au\u00dfenparkplatz und eine Terrasse auf der Galerie von 14,40 m2, die KOSTENLOS sind!!<br \/>\n.<br \/>\nDas Geb\u00e4ude verf\u00fcgt \u00fcber einen Aufzug.<br \/>\n.<br \/>\nGrundrissansicht Wohnung Nummer 10.<br \/>\n.<br \/>\nDie Dokumentation ist in Ordnung.<br \/>\n.<br \/>\nGeplanter Einzug 06\/2025.<br \/>\n.<br \/>\nM\u00f6glichkeit zum Kauf einer Garage:<br \/>\n Garage 1 &#8211; 36.180,00 Euro<br \/>\n Garage 2 &#8211; 67.140,00 Euro<br \/>\n Garage 3 &#8211; 44.280,00 Euro<br \/>\n Garage 4 \u2013 80.100,00 Euro.<\/p>\n","protected":false},"author":7,"featured_media":1130450,"template":"","meta":{"_acf_changed":false,"footnotes":""},"building_condition":[252],"features":[284,172,173],"haus_typ":[],"heating":[175],"kategorie":[253],"location_feature":[259,256],"parking":[],"utility":[179,232,285,180,257,260],"class_list":["post-717364","immobilien","type-immobilien","status-publish","has-post-thumbnail","hentry","building_condition-neu","features-aufzug","features-balkon-de","features-terrasse","heating-wechselstrom","kategorie-ferienwohnung","location_feature-seeblick","location_feature-pogled-na-more","utility-elektrizitaet","utility-dsl-de","utility-kanal-de","utility-telefon","utility-voda","utility-wasser-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN<\/title>\n<meta name=\"description\" content=\"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN\" \/>\n<meta property=\"og:description\" content=\"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/\" \/>\n<meta property=\"og:site_name\" content=\"CARPE SOL IMMOBILIEN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/\",\"url\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/\",\"name\":\"PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN\",\"isPartOf\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg\",\"datePublished\":\"2026-06-27T02:14:05+00:00\",\"description\":\"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige\",\"breadcrumb\":{\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/carpe-sol.com\/hr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PAG &#8211; POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#website\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"name\":\"CARPE SOL IMMOBILIEN\",\"description\":\"Leben in Kroatien - Immobilien in Kroatien\",\"publisher\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#organization\",\"name\":\"CARPE SOL IMMOBILIEN\",\"url\":\"https:\/\/carpe-sol.com\/hr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":393,\"height\":72,\"caption\":\"CARPE SOL IMMOBILIEN\"},\"image\":{\"@id\":\"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN","description":"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/","og_locale":"de_DE","og_type":"article","og_title":"PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN","og_description":"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige","og_url":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/","og_site_name":"CARPE SOL IMMOBILIEN","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/","url":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/","name":"PAG - POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!! - CARPE SOL IMMOBILIEN","isPartOf":{"@id":"https:\/\/carpe-sol.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage"},"image":{"@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage"},"thumbnailUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg","datePublished":"2026-06-27T02:14:05+00:00","description":"Pag \u2013 Povljana, Maisonette-Wohnung mit zwei Schlafzimmern, 122,39 m2, zu verkaufen im zweiten Stock eines Wohngeb\u00e4udes, Baujahr 2024, hochwertige","breadcrumb":{"@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#primaryimage","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2026\/06\/39792-ACCamera_27-1.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/carpe-sol.com\/immobilien\/pag-povljana-wohnung-zu-verkaufen-12239-m2-aussicht-neu-aufzug-lage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carpe-sol.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/carpe-sol.com\/hr\/vlasni\u0161tvo\/"},{"@type":"ListItem","position":3,"name":"PAG &#8211; POVLJANA, WOHNUNG ZU VERKAUFEN 122,39 M2, AUSSICHT, NEU, AUFZUG, LAGE!!!!"}]},{"@type":"WebSite","@id":"https:\/\/carpe-sol.com\/hr\/#website","url":"https:\/\/carpe-sol.com\/hr\/","name":"CARPE SOL IMMOBILIEN","description":"Leben in Kroatien - Immobilien in Kroatien","publisher":{"@id":"https:\/\/carpe-sol.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carpe-sol.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/carpe-sol.com\/hr\/#organization","name":"CARPE SOL IMMOBILIEN","url":"https:\/\/carpe-sol.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/carpe-sol.com\/wp-content\/uploads\/2023\/04\/logo.png","width":393,"height":72,"caption":"CARPE SOL IMMOBILIEN"},"image":{"@id":"https:\/\/carpe-sol.com\/hr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/717364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/types\/immobilien"}],"author":[{"embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/immobilien\/717364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media\/1130450"}],"wp:attachment":[{"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/media?parent=717364"}],"wp:term":[{"taxonomy":"building_condition","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/building_condition?post=717364"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/features?post=717364"},{"taxonomy":"haus_typ","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/haus_typ?post=717364"},{"taxonomy":"heating","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/heating?post=717364"},{"taxonomy":"kategorie","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/kategorie?post=717364"},{"taxonomy":"location_feature","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/location_feature?post=717364"},{"taxonomy":"parking","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/parking?post=717364"},{"taxonomy":"utility","embeddable":true,"href":"https:\/\/carpe-sol.com\/de\/wp-json\/wp\/v2\/utility?post=717364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}